{"id":10544,"date":"2025-12-24T17:22:54","date_gmt":"2025-12-24T16:22:54","guid":{"rendered":"https:\/\/www.feuerwehr-attendorn.de\/www\/?p=10544"},"modified":"2025-12-24T17:23:57","modified_gmt":"2025-12-24T16:23:57","slug":"weihnachtsgruss-der-freiwilligen-feuerwehr-der-hansestadt-attendorn","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-attendorn.de\/www\/2025\/12\/24\/weihnachtsgruss-der-freiwilligen-feuerwehr-der-hansestadt-attendorn\/","title":{"rendered":"Weihnachtsgru\u00df der Freiwilligen Feuerwehr der Hansestadt Attendorn"},"content":{"rendered":"\n<p>Liebe B\u00fcrgerinnen und B\u00fcrger der Stadt Attendorn, liebe Kameradinnen und Kameraden,<br>in wenigen Tagen neigt sich das Jahr dem Ende zu \u2013 Zeit, kurz auf das Jahr 2025 zur\u00fcckzublicken. Es war ein Jahr mit vielen Ereignissen, besonderen Eins\u00e4tzen und gro\u00dfen Ver\u00e4nderungen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"744\" src=\"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2025\/12\/1-1024x744.jpg\" alt=\"\" class=\"wp-image-10545\" srcset=\"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2025\/12\/1-1024x744.jpg 1024w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2025\/12\/1-300x218.jpg 300w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2025\/12\/1-768x558.jpg 768w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2025\/12\/1-1536x1115.jpg 1536w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2025\/12\/1.jpg 1921w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Vor allem im Bereich Technik und Ausstattung hat sich viel getan: Neue Fahrzeuge, neue Technik, neue Beladung. Auf dem Foto seht ihr vier neue LF 10, die f\u00fcr die Einheiten Lichtringhausen, Repetal, Ihnetal und Windhausenvorgesehen sind. Allein drei dieser Fahrzeuge wurden in diesem Jahr beschafft. Moderne Fahrzeuge bedeuten jedoch nicht nur Fortschritt, sondern auch Verantwortung: F\u00fcr alle Kameradinnen und Kameraden hei\u00dft das, schulen, \u00fcben und sich immer wieder neu auf Technik und Abl\u00e4ufe einzustellen, um im Ernstfall bestm\u00f6glich helfen zu k\u00f6nnen.<br>Kurz vor Jahresende hie\u00df es auch f\u00fcr die L\u00f6schgruppe Listerscheid: Tasche packen. Das alte Ger\u00e4tehaus wurde verlassen, und der Umzug in ein Interimsdomizil ist erfolgt \u2013 ein erster wichtiger Schritt in Richtung Neubau.<br>Dieses Jahr hat uns zudem gezeigt, wie schnell wir gefordert sein k\u00f6nnen. Zwei gro\u00dfe Brandereignisse innerhalb von weniger als 48 Stunden verlangten den Einsatzkr\u00e4ften alles ab. Auch ein Tag vor Heiligabend war die Feuerwehr stark gefordert \u2013 f\u00fcnf Eins\u00e4tze an nur einem Tag. \u00dcber die Weihnachtsfeiertage und den Jahreswechsel ist die Feuerwehr Attendorn nat\u00fcrlich weiterhin 24\/7 Einsatzbereit und das Ehrenamtlich.<\/p>\n\n\n\n<p>F\u00fcr diese Einsatzbereitschaft, den starken Zusammenhalt und das gro\u00dfe Engagement bedanken wir uns herzlich bei allen Kameradinnen und Kameraden.<br>Wir w\u00fcnschen allen B\u00fcrgerinnen und B\u00fcrgern, unseren Unterst\u00fctzern sowie allen Einsatzkr\u00e4ften frohe und besinnliche Weihnachten \ud83c\udf84 und einen guten Rutsch ins neue Jahr 2026 \ud83c\udf86<\/p>\n\n\n\n<p>Eure Feuerwehr Attendorn \ud83d\ude92<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe B\u00fcrgerinnen und B\u00fcrger der Stadt Attendorn, liebe Kameradinnen und Kameraden,in wenigen Tagen neigt sich das Jahr dem Ende zu \u2013 Zeit, kurz auf das Jahr 2025 zur\u00fcckzublicken. Es war ein Jahr mit vielen Ereignissen, besonderen Eins\u00e4tzen und gro\u00dfen Ver\u00e4nderungen.&hellip;<\/p>\n","protected":false},"author":6,"featured_media":10546,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","cybocfi_hide_featured_image":"","footnotes":""},"categories":[5,1],"tags":[],"class_list":["post-10544","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/10544","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/comments?post=10544"}],"version-history":[{"count":1,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/10544\/revisions"}],"predecessor-version":[{"id":10547,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/10544\/revisions\/10547"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/media\/10546"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/media?parent=10544"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/categories?post=10544"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/tags?post=10544"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}