{"id":3238,"date":"2018-05-11T10:16:40","date_gmt":"2018-05-11T08:16:40","guid":{"rendered":"http:\/\/www.feuerwehr-attendorn.de\/wordpress\/?p=3238"},"modified":"2018-05-11T10:16:40","modified_gmt":"2018-05-11T08:16:40","slug":"einsatzuebung-am-biggedamm","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-attendorn.de\/www\/2018\/05\/11\/einsatzuebung-am-biggedamm\/","title":{"rendered":"Einsatz\u00fcbung am Biggedamm"},"content":{"rendered":"<p>Feuer im Kiosk am Biggedamm, Personen in Gefahr! So lautete in dieser Woche der Einsatzauftrag im Rahmen einer Einsatz\u00fcbung des L\u00f6schzuges Attendorn. Angenommene Lage war ein Brand, der im K\u00fcchenbereich des Kiosk entstanden war und sich auf das restliche Geb\u00e4ude ausbreitete. Bei dieser \u00dcbung galt es zwei Schwerpunkte abzuarbeiten. W\u00e4hrend die ersten Kr\u00e4fte vor Ort die Menschenrettung mit zwei Trupps unter Atemschutz einleiteten, wurde durch die restlichen Einsatzkr\u00e4fte die L\u00f6schwasserversorgung aufgebaut.<\/p>\n<figure id=\"attachment_3244\" aria-describedby=\"caption-attachment-3244\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3244 size-full\" src=\"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/wp-content\/uploads\/2018\/05\/ueb05.jpg\" alt=\"\" width=\"1000\" height=\"750\" srcset=\"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb05.jpg 1000w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb05-300x225.jpg 300w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb05-768x576.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-3244\" class=\"wp-caption-text\">Durch zwei Trupps wurde die Menschenrettung unter Atemschutz durchgef\u00fchrt, dichter Rauch sorgte f\u00fcr nahezu reale Sichtbedingungen<\/figcaption><\/figure>\n<figure id=\"attachment_3243\" aria-describedby=\"caption-attachment-3243\" style=\"width: 1000px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3243 size-full\" src=\"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/wp-content\/uploads\/2018\/05\/ueb04.jpg\" alt=\"\" width=\"1000\" height=\"750\" srcset=\"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb04.jpg 1000w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb04-300x225.jpg 300w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb04-768x576.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption id=\"caption-attachment-3243\" class=\"wp-caption-text\">Parallel dazu wurde eine L\u00f6schwasserversorgung aufgebaut<\/figcaption><\/figure>\n<p>Dazu war es erforderlich eine Wasserentnahme am sogenannten Ihneschuss, rund 25 H\u00f6henmeter unterhalb der Einsatzstelle, zu einzurichten. \u00dcber eine gut 350 Meter lange Schlauchleitung wurde das Wasser dann zur Einsatzstelle bef\u00f6rdert. Ein recht aufw\u00e4ndiges Unterfangen, wenn man bedenkt, dass die Biggetalsperre nur wenige Meter entfernt liegt. Der Hauptdamm mit seiner ca. 30 Grad steilen, asphaltierten Oberfl\u00e4che, bietet jedoch keine sichere M\u00f6glichkeit dort Wasser zu entnehmen, schlie\u00dflich mussten bei der Sanierung der Apshaltschicht vor drei Jahren auch alle Arbeitsger\u00e4te an Seilwinden gef\u00fchrt werden.<\/p>\n<figure id=\"attachment_3240\" aria-describedby=\"caption-attachment-3240\" style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3240 size-full\" src=\"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/wp-content\/uploads\/2018\/05\/ueb01.jpg\" alt=\"\" width=\"1500\" height=\"1125\" srcset=\"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb01.jpg 1500w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb01-300x225.jpg 300w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb01-1024x768.jpg 1024w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb01-768x576.jpg 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><figcaption id=\"caption-attachment-3240\" class=\"wp-caption-text\">Circa 25 H\u00f6henmeter unterhalb der Einsatzstelle wurde L\u00f6schwasser aus der Ihne am sogenannten &#8222;Ihneschuss&#8220; entnommen<\/figcaption><\/figure>\n<figure id=\"attachment_3242\" aria-describedby=\"caption-attachment-3242\" style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3242 size-full\" src=\"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/wp-content\/uploads\/2018\/05\/ueb03.jpg\" alt=\"\" width=\"1500\" height=\"1125\" srcset=\"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb03.jpg 1500w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb03-300x225.jpg 300w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb03-1024x768.jpg 1024w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb03-768x576.jpg 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><figcaption id=\"caption-attachment-3242\" class=\"wp-caption-text\">\u00dcber eine Strecke von gut 350 Metern wurde das Wasser dann zur Einsatzstelle gepumpt<\/figcaption><\/figure>\n<p>Nach relativ kurzer Zeit konnten die Ziele der \u00dcbung erreicht werden. In einer anschlie\u00dfenenden Nachbesprechung wurden positive und negative Dinge herausgearbeitet.<\/p>\n<figure id=\"attachment_3241\" aria-describedby=\"caption-attachment-3241\" style=\"width: 1500px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3241 size-full\" src=\"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/wp-content\/uploads\/2018\/05\/ueb02.jpg\" alt=\"\" width=\"1500\" height=\"1125\" srcset=\"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb02.jpg 1500w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb02-300x225.jpg 300w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb02-1024x768.jpg 1024w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/05\/ueb02-768x576.jpg 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><figcaption id=\"caption-attachment-3241\" class=\"wp-caption-text\">Am Ihneschuss befindet sich eine Saugstelle f\u00fcr die L\u00f6schwasserentnahme durch die Feuerwehr. Solche Bereiche sollten von parkenden Fahrzeug freigehalten werden.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Feuer im Kiosk am Biggedamm, Personen in Gefahr! So lautete in dieser Woche der Einsatzauftrag im Rahmen einer Einsatz\u00fcbung des L\u00f6schzuges Attendorn. Angenommene Lage war ein Brand, der im K\u00fcchenbereich des Kiosk entstanden war und sich auf das restliche Geb\u00e4ude&hellip;<\/p>\n","protected":false},"author":4,"featured_media":3239,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","cybocfi_hide_featured_image":"","footnotes":""},"categories":[2,9,11],"tags":[],"class_list":["post-3238","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-einsatzabteilung","category-lz-attendorn","category-uebungsbericht"],"_links":{"self":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/3238","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/comments?post=3238"}],"version-history":[{"count":0,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/3238\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/media\/3239"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/media?parent=3238"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/categories?post=3238"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/tags?post=3238"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}