{"id":3669,"date":"2018-07-29T09:35:13","date_gmt":"2018-07-29T07:35:13","guid":{"rendered":"http:\/\/www.feuerwehr-attendorn.de\/wordpress\/?p=3669"},"modified":"2018-07-29T09:35:13","modified_gmt":"2018-07-29T07:35:13","slug":"einsatz-1-bereitschaft-waldbrand-in-altena","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-attendorn.de\/www\/2018\/07\/29\/einsatz-1-bereitschaft-waldbrand-in-altena\/","title":{"rendered":"Einsatz 1. Bereitschaft: Waldbrand in Altena"},"content":{"rendered":"<p>Am Freitag (27.07.18) wurde um 09:55 Uhr die erste Bereitschaft des Regierungsbezirks Arnsberg zur \u00fcber\u00f6rtliche Hilfe bei einem Waldbrand in Altena (M\u00e4rkischer Kreis) alarmiert. Dort brannten seit Donnerstag Nachmittag rund 10.000 Quadratmeter Wald an einem Steilhang. Die Feuerwehr Attendorn ist mit dem Tankl\u00f6schfahrzeug der L\u00f6schgruppe Listerscheid Teil dieser Bereitschaft (weitere Infos dazu unten).<\/p>\n<p>Sammelpunkt f\u00fcr die Einsatzkr\u00e4fte aus den Kreisen Olpe und Siegen-Wittgenstein war ein Parkplatz an der Anschlusstelle Drolshagen der BAB 45. Die Einsatzkr\u00e4fte aus dem Hochsauerlandkreis fuhren die Strecke auf Grund der r\u00e4umlichen Gegebenheit eigenst\u00e4ndig an. Vom Sammelpunkt aus fuhr der Fahrzeugverband dann zun\u00e4chst in einen Bereitstellunsgraum in Iserlohn. Dort gab es eine kleine St\u00e4rkung, bevor der mehrst\u00fcndige Einsatz vor Ort begann.<\/p>\n<p>Das Feuer war bereits weitestgehend unter Kontrolle gebracht, einige Glutnester loderten jedoch immer wieder auf. Da der Steilhang, welcher ohnehin schlecht zu begehen war, auch noch durch Kampfmittel aus dem zweiten Weltkrieg belastet war, blieben alle Einsatzkr\u00e4fte auf Distanz und brachten L\u00f6schwasser mit gro\u00dfen Wurfweiten in die Waldfl\u00e4che ein. Das Tankl\u00f6schfahrzeug aus Listerscheid wurde dabei auf einer \u00fcber 700 Meter langen Strecke im Pendelverkehr eingesetzt. Zun\u00e4chst wurde das Wasser an einer \u00dcbergabestelle an der Lenne aufgenommen, dort war die Feuerwehr Olpe bereits seit dem Vorabend mit einem Hochleistungs-Wasserf\u00f6rdersystem im Einsatz. Sp\u00e4ter erfolgte die Aufnahme des Wassers an einem Wasserbeh\u00e4lter an einer anderen Stelle. Durch das THW war die Pendelstrecke so abgesichert, dass ein Umlauf im Einbahnstra\u00dfenverkehr durchgef\u00fchrt werden konnte.<\/p>\n<p><a href=\"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/wp-content\/uploads\/2018\/07\/altena4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-3675\" src=\"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/wp-content\/uploads\/2018\/07\/altena4-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" \/><\/a><\/p>\n<p>Gegen 19:30 Uhr wurden die Einsatzkr\u00e4fte der ersten Bereitschaft abgel\u00f6st und konnten die Reise in das verdiente Wochenende antreten. Aus dem Kreis Olpe waren ein Einsatzleitwagen aus Finnentrop-Heggen, ein Tankl\u00f6schfahrzeug aus Lennestadt-Meggen, ein L\u00f6schgruppenfahrzeug und ein Ger\u00e4tewagen-Logisitk aus Lennestadt-Grevenbr\u00fcck und aus Kirchhundem-Hofolpe ein L\u00f6schgruppenfahrzeug und ein Mannschaftstransportfahrzeug im \u00fcber\u00f6rtlichen Einsatz. Au\u00dferdem war der Wasserf\u00f6rderzug aus Olpe bereits seit Donnerstagabend vor Ort.<\/p>\n<p><a href=\"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/wp-content\/uploads\/2018\/07\/altena1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3672\" src=\"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/wp-content\/uploads\/2018\/07\/altena1.jpg\" alt=\"\" width=\"1000\" height=\"750\" srcset=\"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/07\/altena1.jpg 1000w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/07\/altena1-300x225.jpg 300w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/07\/altena1-768x576.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<h2>Hintergrundinformation zu den Feuerwehrbereitschaften<\/h2>\n<p>In Nordrhein-Westfalen gibt es ein Landeskonzept zur vorgeplanten \u00fcber\u00f6rtlichen Hilfe<a href=\"http:\/\/www.idf.nrw.de\/service\/downloads\/pdf\/interschutz_2015\/medien_interschutz_poster_2_brandschutz_wasserrettung.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-3676 size-medium\" src=\"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/wp-content\/uploads\/2018\/07\/2_brandschutz_wasserrettung-214x300.jpg\" alt=\"\" width=\"214\" height=\"300\" srcset=\"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/07\/2_brandschutz_wasserrettung-214x300.jpg 214w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2018\/07\/2_brandschutz_wasserrettung.jpg 647w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a>. Dieses Konzept sieht vor, dass jeder der f\u00fcnf Regierungsbezirke eine sogenannte Bezirksabteilung zur \u00fcber\u00f6rtlichen Hilfe stellt. Eine Bezirksabteilung besteht aus der Abteilungsf\u00fchrung und f\u00fcnf Bezirksbereitschaften. Mindestens zwei Kreise oder kreisfreie St\u00e4dte stellen Personal und Material f\u00fcr eine Bereitschaft. Die Kreise Olpe, Siegen-Wittgenstein und der Hochsauerlandkreis bilden zusammen die erste Bereitschaft, wobei die Nummerierung fortlaufend gew\u00e4hlt ist und ansonsten keinerlei Bedeutung hat. Unmittelbar angrenzend bilden der M\u00e4rkische Kreis und die Stadt Hagen zum Beispiel die vierte Bereitschaft.<\/p>\n<p>Jede Bereitschaft besteht wiederum aus der Bereitschaftsf\u00fchrung und vier L\u00f6schz\u00fcgen. Hinzu kommt ein Logistikzug. Je nach Bedarf werden die Z\u00fcge durch Sonderfahrzeuge erg\u00e4nzt, bei Waldbr\u00e4nden durch Tankl\u00f6schfahrzeuge, bei technischen Hilfeleistungen durch Drehleitern und R\u00fcstwagen. Jede Bereitschaft kommt somit auf rund 125 Einsatzkr\u00e4fte mit 20 Fahrzeugen. Die gesamte Abteilung eines Regierungsbezirks verf\u00fcgt \u00fcber mehr als 625 Einsatzkr\u00e4fte mit \u00fcber 100 Fahrzeugen. Jeder Kreis und jede kreisfreie Stadt kann jederzeit auf diese landesweiten Kapazit\u00e4ten zur\u00fcckgreifen. Dabei k\u00f6nnen die Bereitschaften einzeln, aber auch die gesamte Abteilung eines Regierungsbezirks in Marsch gesetzt werden.<\/p>\n<p>Landesweit stehen somit permanent \u00fcber 3000 Einsatzkr\u00e4fte mit \u00fcber 500 Fahrzeugen f\u00fcr die \u00fcber\u00f6rtliche Hilfe bereit. Da zum Beispiel aus Attendorn nur ein Tankl\u00f6schfahrzeug f\u00fcr die Bereitschaft eingeplant ist, bleibt die \u00f6rtliche Feuerwehr immer ausreichend leistungsf\u00e4hig f\u00fcr ihre eigenen Aufgaben.<\/p>\n<p>Das Konzept erm\u00f6glicht die schnelle und organisierte Verlegung von starken Kr\u00e4ften im gesamten Land. So war die erste Bereitschaft 2010 zum Beispiel im \u00f6stlichen M\u00fcnsterland bei einer gro\u00dffl\u00e4chigen Hochwasserlage im Einsatz.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Freitag (27.07.18) wurde um 09:55 Uhr die erste Bereitschaft des Regierungsbezirks Arnsberg zur \u00fcber\u00f6rtliche Hilfe bei einem Waldbrand in Altena (M\u00e4rkischer Kreis) alarmiert. Dort brannten seit Donnerstag Nachmittag rund 10.000 Quadratmeter Wald an einem Steilhang. Die Feuerwehr Attendorn ist&hellip;<\/p>\n","protected":false},"author":4,"featured_media":3674,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","cybocfi_hide_featured_image":"","footnotes":""},"categories":[5,2,8,10],"tags":[],"class_list":["post-3669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-einsatzabteilung","category-einsatzbericht","category-lz-ihnetal"],"_links":{"self":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/3669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/comments?post=3669"}],"version-history":[{"count":0,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/3669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/media\/3674"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/media?parent=3669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/categories?post=3669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/tags?post=3669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}