{"id":3885,"date":"2018-09-21T18:05:09","date_gmt":"2018-09-21T16:05:09","guid":{"rendered":"http:\/\/www.feuerwehr-attendorn.de\/wordpress\/?p=3885"},"modified":"2018-09-21T18:05:09","modified_gmt":"2018-09-21T16:05:09","slug":"3885","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-attendorn.de\/www\/2018\/09\/21\/3885\/","title":{"rendered":"Feuer in leerstehendem Industriekomplex"},"content":{"rendered":"<p>Feuerwehr, Rettungsdienst und Polizei wurden um 14:16 Uhr am heutigen Nachmittag zu einem Brand in einem leerstehenden Industriekomplex in Attendorn, Am Wassertor, gerufen. Beim Eintreffen der Feuerwehr brannte eine Produktionsanlage in einem ansonsten leerstehenden Teil einer ehemaligen Produktionshalle.<\/p>\n<p>Zur Brandbek\u00e4mfung wurde ein Trupp unter Atemschutz mit einem Strahlrohr eingesetzt. Weitere Einsatzk\u00e4fte standen zur Absicherung des eigenen Personals und als Reserve in Bereitstellung. Personen wurden vor Ort nicht mehr angetroffen. Das Feuer war in kurzer Zeit in der Gewalt der Einsatzkr\u00e4fte.<\/p>\n<p>Das Dach der Halle wurde \u00fcber die Drehleiter kontrolliert, eine Brandausbreitung konnte zu diesem Zeitpunkt nicht festgestellt werden.<\/p>\n<p>Die Feuerwehr war mit 36 Einsatzkr\u00e4ften und sieben Fahrzeugen des L\u00f6schzuges Attendorn und der Tagwache, welche durch Mitarbeiter der Firma Mubea gestellt wird, eine gute Stunde im Einsatz.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Feuerwehr, Rettungsdienst und Polizei wurden um 14:16 Uhr am heutigen Nachmittag zu einem Brand in einem leerstehenden Industriekomplex in Attendorn, Am Wassertor, gerufen. Beim Eintreffen der Feuerwehr brannte eine Produktionsanlage in einem ansonsten leerstehenden Teil einer ehemaligen Produktionshalle. Zur Brandbek\u00e4mfung&hellip;<\/p>\n","protected":false},"author":4,"featured_media":3886,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","cybocfi_hide_featured_image":"","footnotes":""},"categories":[5,2,8,9],"tags":[],"class_list":["post-3885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-einsatzabteilung","category-einsatzbericht","category-lz-attendorn"],"_links":{"self":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/3885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/comments?post=3885"}],"version-history":[{"count":0,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/3885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/media\/3886"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/media?parent=3885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/categories?post=3885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/tags?post=3885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}