{"id":5665,"date":"2020-06-30T07:28:11","date_gmt":"2020-06-30T05:28:11","guid":{"rendered":"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/?p=5665"},"modified":"2020-06-30T07:28:11","modified_gmt":"2020-06-30T05:28:11","slug":"brand-in-einem-waldstueck-beschaeftigt-feuerwehr","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-attendorn.de\/www\/2020\/06\/30\/brand-in-einem-waldstueck-beschaeftigt-feuerwehr\/","title":{"rendered":"Brand in einem Waldst\u00fcck besch\u00e4ftigt Feuerwehr"},"content":{"rendered":"<p>Der L\u00f6schzug Attendorn wurde am heutigen Dienstag um 05.42 Uhr zu einem Vegetationsbrand in der Herforder Stra\u00dfe alarmiert. Beim Eintreffen brannten ca. 30 m\u00b2 in unwegsamen Gel\u00e4nde. Zur Brandbek\u00e4mpfung wurde ein Trupp unter Atemschutz eingesetzt.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-5668\" src=\"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/wp-content\/uploads\/2020\/06\/DSC_0129-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1711\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der L\u00f6schzug Attendorn wurde am heutigen Dienstag um 05.42 Uhr zu einem Vegetationsbrand in der Herforder Stra\u00dfe alarmiert. Beim Eintreffen brannten ca. 30 m\u00b2 in unwegsamen Gel\u00e4nde. Zur Brandbek\u00e4mpfung wurde ein Trupp unter Atemschutz eingesetzt.<\/p>\n","protected":false},"author":2,"featured_media":5666,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","cybocfi_hide_featured_image":"","footnotes":""},"categories":[5,2,8,9],"tags":[],"class_list":["post-5665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-einsatzabteilung","category-einsatzbericht","category-lz-attendorn"],"_links":{"self":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/5665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/comments?post=5665"}],"version-history":[{"count":0,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/5665\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/media\/5666"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/media?parent=5665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/categories?post=5665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/tags?post=5665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}