{"id":6067,"date":"2021-03-09T12:37:23","date_gmt":"2021-03-09T11:37:23","guid":{"rendered":"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/?p=6067"},"modified":"2021-03-09T12:37:23","modified_gmt":"2021-03-09T11:37:23","slug":"brand-im-dachgeschoss-eines-wohnhauses","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-attendorn.de\/www\/2021\/03\/09\/brand-im-dachgeschoss-eines-wohnhauses\/","title":{"rendered":"Brand im Dachgeschoss eines Wohnhauses"},"content":{"rendered":"<figure id=\"attachment_6065\" aria-describedby=\"caption-attachment-6065\" style=\"width: 1292px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6065\" src=\"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/wp-content\/uploads\/2021\/03\/Dachgeschossbrand.jpg\" alt=\"\" width=\"1292\" height=\"831\" srcset=\"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2021\/03\/Dachgeschossbrand.jpg 1292w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2021\/03\/Dachgeschossbrand-300x193.jpg 300w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2021\/03\/Dachgeschossbrand-1024x659.jpg 1024w, https:\/\/www.feuerwehr-attendorn.de\/www\/wp-content\/uploads\/2021\/03\/Dachgeschossbrand-768x494.jpg 768w\" sizes=\"auto, (max-width: 1292px) 100vw, 1292px\" \/><figcaption id=\"caption-attachment-6065\" class=\"wp-caption-text\">Bild: Polizei Olpe<\/figcaption><\/figure>\n<p>Der L\u00f6schzug Attendorn wurde am vergangenen Samstag mit dem Einsatzstichwort \u201eFeuer 2 \u2013 Dachstuhlbrand\u201c in die Stra\u00dfe Wippeskuhlen gerufen. Beim Eintreffen des ersten L\u00f6schfahrzeuges und der Drehleiter, knapp sieben Minuten nach dem Notruf, drang schwarzer Brandrauch aus einem Fenster im Dachgeschoss und aus mehreren \u00d6ffnungen in der Dachhaut. Personen befanden sich nicht mehr im Geb\u00e4ude. Eine Person, welche Rauchgasen ausgesetzt war, wurde dem Rettungsdienst, welcher mit einem Rettunsgwagen vor Ort war, zur medizinischen Erstversorgung \u00fcbergeben.<\/p>\n<p>Umgehend wurde ein Trupp unter Atemschutz in das Geb\u00e4ude vorgeschickt und die Drehleiter in Stellung gebracht. Da ein \u00dcbergreifen des Feuers auf das Dachgeschoss zun\u00e4chst nicht ausgeschlossen werden konnte erh\u00f6hte der Einsatzleiter das Einsatzstichwort nach der ersten Erkundung auf \u201eFeuer 3\u201c, was eine Alarmierung weiterer Kr\u00e4fte des L\u00f6schzuges Ennest zur Folge hatte.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6066\" src=\"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/wp-content\/uploads\/2021\/03\/DSC_0388-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1711\" \/><\/p>\n<p>Der eingesetzte Trupp konnte schnell ein Feuer in einer K\u00fcche im Dachgeschoss ausfindig machen und dieses in seine Gewalt bringen. Im weiteren Verlauf wurden zwei weitere Trupps unter Atemschutz zu Nachl\u00f6scharbeiten eingesetzt, welche Teile der Dachkonstruktion von innen und au\u00dfen \u00f6ffneten und auf Brandnester kontrollierten.<\/p>\n<p>Zur Aufnahme und Abtransport von verschmutztem Material der Feuerwehr wurde der Ger\u00e4tewagen-Logistik des L\u00f6schzuges Repetal nachalarmiert.<\/p>\n<p>Das Deutsche Rote Kreuz stellte vor Ort den medizinischen Eigenschutz f\u00fcr die eingesetzten Kr\u00e4fte und versorgte diese mit Kalt- und Warmgetr\u00e4nken.<\/p>\n<p>Die Feuerwehr war mit zwei F\u00fchrungsfahrzeugen, f\u00fcnf L\u00f6schfahrzeugen, einer Drehleiter, einem Tankl\u00f6schfahrzeug, einem Ger\u00e4tewagen, einem Mannschaftstransportfahrzeug und dem Vorausl\u00f6schfahrzeug, sowie 37 Einsatzkr\u00e4ften vor Ort. Der Einsatz endete f\u00fcr die letzten Kr\u00e4fte gegen 20:00 Uhr. Im Anschluss daran waren noch zahlreiche T\u00e4tigkeiten zur Wiederherstellung der Einsatzbereitschaft erforderlich.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der L\u00f6schzug Attendorn wurde am vergangenen Samstag mit dem Einsatzstichwort \u201eFeuer 2 \u2013 Dachstuhlbrand\u201c in die Stra\u00dfe Wippeskuhlen gerufen. Beim Eintreffen des ersten L\u00f6schfahrzeuges und der Drehleiter, knapp sieben Minuten nach dem Notruf, drang schwarzer Brandrauch aus einem Fenster im&hellip;<\/p>\n","protected":false},"author":4,"featured_media":6065,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","cybocfi_hide_featured_image":"","footnotes":""},"categories":[5,2,8,9,7],"tags":[],"class_list":["post-6067","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-einsatzabteilung","category-einsatzbericht","category-lz-attendorn","category-lz-ennest"],"_links":{"self":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/6067","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/comments?post=6067"}],"version-history":[{"count":0,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/6067\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/media\/6065"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/media?parent=6067"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/categories?post=6067"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/tags?post=6067"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}