{"id":8065,"date":"2023-06-28T08:59:58","date_gmt":"2023-06-28T06:59:58","guid":{"rendered":"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/?p=8065"},"modified":"2023-06-28T08:59:58","modified_gmt":"2023-06-28T06:59:58","slug":"neue-waldbrandausstattung","status":"publish","type":"post","link":"https:\/\/www.feuerwehr-attendorn.de\/www\/2023\/06\/28\/neue-waldbrandausstattung\/","title":{"rendered":"Neue Waldbrandausstattung"},"content":{"rendered":"<figure id=\"attachment_8066\" aria-describedby=\"caption-attachment-8066\" style=\"width: 2560px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8066 size-full\" src=\"https:\/\/www.feuerwehr-attendorn.de\/wordpress\/wp-content\/uploads\/2023\/06\/IMG_1948-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" \/><figcaption id=\"caption-attachment-8066\" class=\"wp-caption-text\">Winfried Kl\u00f6wer (AK Waldbrand), Dr. Tobias Bock (Leiter der Feuerwehr), Frank Schmidt (stv. Leiter der Feuerwehr), Peter Heuel (stv. Leiter der Feuerwehr), Jens M\u00fcller (AK Waldbrand), Leon Hunfeld (mit neuer Schutzkleidung aus aktuellem Trageversuch) (v.l.n.r.)<\/figcaption><\/figure>\n<p>Aufgrund der zunehmenden Gefahr von Wald- und Vegetationsbr\u00e4nden und aus der Erfahrung des gro\u00dfen Waldbrandes in Attendorn im August 2022 wurde von dem Arbeitskreis Wald- und Vegetationsbrandbek\u00e4mpfung ein Konzept zur taktischen Vorgehensweise und weiterer Beschaffungsma\u00dfnahmen f\u00fcr die Feuerwehr Attendorn erstellt.<\/p>\n<p>Bereits kurz nach dem Waldbrand wurden Gespr\u00e4che mit einer gro\u00dfen Anzahl von Landwirten aus dem Stadtgebiet gef\u00fchrt. Alle anwesenden Landwirte sagten eine spontane Unterst\u00fctzung zum Heranfahren von gro\u00dfen Mengen L\u00f6schwasser w\u00e4hrend eines k\u00fcnftigen Einsatzes im Waldgebiet zu. \u201eHier geht ein gro\u00dfer Dank an alle Beteiligten,\u201c berichtet Winfried Kl\u00f6wer vom L\u00f6schzug Attendorn.<\/p>\n<p>Im Jahr 2022 konnte bereits jede L\u00f6scheinheit mit einer Grundausstattung an Ger\u00e4tschaften und Schlauchmaterial ausgestattet werden. Um hier aber weiter gut aufgestellt zu sein, wurde eine weitere, gr\u00f6\u00dfere Beschaffungsma\u00dfnahme vor kurzem abgeschlossen. Diese Ausstattung, gelagert in Rollwagen, wird dann im Einsatzfall von einem Logistikfahrzeug der Einsatzstelle zugef\u00fchrt.<\/p>\n<p>Da die Beschaffung nun komplett ist, wurde diese jetzt offiziell im Rahmen des Feuerwehrfestes in Attendorn in Dienst gestellt.<\/p>\n<ul>\n<li>Unter anderem wurden zehn sogenannte Kreisregner beschafft. Diese Ger\u00e4te k\u00f6nnen autark bei Nachl\u00f6scharbeiten eingesetzt werden und \u00fcber mehrere Stunden &#8211; pro Ger\u00e4t &#8211; eine Brandfl\u00e4che von ca. 1.600 m\u00b2 bew\u00e4ssern.<\/li>\n<li>Zur Brandbek\u00e4mpfung werden 10 Stck. Schnellangriffstaschen mit je 30 m Schlauchmaterial, Strahlrohr und Gesichtsschutz vorgehalten.<\/li>\n<li>Des Weiteren wurde zus\u00e4tzliches Schlauchmaterial, L\u00f6schwasserverteiler und Netzmittelzumischer angeschafft.<\/li>\n<li>Der Bestand an L\u00f6schrucks\u00e4cken wurde erweitert.<\/li>\n<li>F\u00fcr die Landwirte wurden spezielle Adapteranschl\u00fcsse f\u00fcr G\u00fcllef\u00e4sser beschafft, um eine reibungslose Wasser\u00fcbergabe zu gew\u00e4hrleisten.<\/li>\n<\/ul>\n<p>Aktuelle Planungen sehen die Beschaffung eines 10.000 Liter Trink-L\u00f6schwasser-Abrollbeh\u00e4lters vor. Zus\u00e4tzlich soll ein transportabler L\u00f6schwasservorratsbeh\u00e4lter mit einem F\u00fcllverm\u00f6gen von ebenfalls 10.000 Liter die Ausstattung der Feuerwehr erg\u00e4nzen. Eine leichte, pers\u00f6nliche Schutzkleidung soll den Feuerwehrkr\u00e4ften in Zukunft diese doch sehr belastende Arbeit erleichtern.<\/p>\n<p>Mit diesen Ma\u00dfnahmen kann sich die Feuerwehr Attendorn nun den zuk\u00fcnftigen Herausforderungen, sowie den prognostizierten vermehrten Wald- und Vegetationsbr\u00e4nden stellen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aufgrund der zunehmenden Gefahr von Wald- und Vegetationsbr\u00e4nden und aus der Erfahrung des gro\u00dfen Waldbrandes in Attendorn im August 2022 wurde von dem Arbeitskreis Wald- und Vegetationsbrandbek\u00e4mpfung ein Konzept zur taktischen Vorgehensweise und weiterer Beschaffungsma\u00dfnahmen f\u00fcr die Feuerwehr Attendorn erstellt.&hellip;<\/p>\n","protected":false},"author":2,"featured_media":8066,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","cybocfi_hide_featured_image":"","footnotes":""},"categories":[5,2],"tags":[],"class_list":["post-8065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","category-einsatzabteilung"],"_links":{"self":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/8065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/comments?post=8065"}],"version-history":[{"count":0,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/posts\/8065\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/media\/8066"}],"wp:attachment":[{"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/media?parent=8065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/categories?post=8065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuerwehr-attendorn.de\/www\/wp-json\/wp\/v2\/tags?post=8065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}